{"id":1630,"date":"2026-05-07T11:05:54","date_gmt":"2026-05-07T11:05:54","guid":{"rendered":"https:\/\/fornosethi.com\/blog\/?st-import=5703b44157b42b600703943e40791d1a"},"modified":"2026-05-07T11:59:26","modified_gmt":"2026-05-07T11:59:26","slug":"about","status":"publish","type":"page","link":"https:\/\/fornosethi.com\/blog\/about\/","title":{"rendered":"About"},"content":{"rendered":"\n\n\n\n\n<figure class=\"wp-block-image size-full is-resized has-custom-border\" style=\"margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"27\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/frill-free-img-1.png\" alt=\"frill free img (1)\" class=\"wp-image-1527\" style=\"border-radius:93px;object-fit:cover;width:250px;height:27px\"\/><\/figure>\n\n\n\n\n\n\n\n\n<figure class=\"wp-block-image size-full\" style=\"margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"108\" height=\"68\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2021\/03\/parcelli.png\" alt=\"parcelli\" class=\"wp-image-264\"\/><\/figure>\n\n\n\n\n\n\n\n\n\n\n\n<figure class=\"wp-block-image size-full is-resized has-custom-border\" style=\"margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1000\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/image-02.jpg\" alt=\"image 02\" class=\"wp-image-1599\" style=\"border-radius:16px;object-fit:cover;width:285px;height:571px\" srcset=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/image-02.jpg 500w, https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/image-02-150x300.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n\n\n<figure class=\"wp-block-image size-full is-resized has-custom-border\" style=\"margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/image-01.jpg\" alt=\"image 01\" class=\"wp-image-1601\" style=\"border-radius:16px;object-fit:cover;width:285px;height:285px\" srcset=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/image-01.jpg 500w, https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/image-01-300x300.jpg 300w, https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/image-01-150x150.jpg 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized has-custom-border\" style=\"margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"226\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/pic34-free-img-300x226-1.jpg\" alt=\"pic34 free img 300x226.jpg\" class=\"wp-image-1305\" style=\"border-radius:16px;object-fit:cover;width:263px;height:198px\"\/><\/figure>\n\n\n\n\n\n\n\n\n\n\n<figure class=\"wp-block-image size-full is-resized\" style=\"margin-top:20px;margin-right:0px;margin-bottom:60px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"27\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/frill-free-img.png\" alt=\"frill free img\" class=\"wp-image-1327\" style=\"object-fit:cover;width:250px;height:27px\"\/><\/figure>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n<figure class=\"wp-block-image size-full is-resized\" style=\"margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"27\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/divider-free-img.png\" alt=\"divider free img\" class=\"wp-image-1629\" style=\"object-fit:cover;width:250px;height:27px\"\/><\/figure>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n<figure class=\"wp-block-image size-full is-resized\" style=\"margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/pic49-free-img.png\" alt=\"pic49 free img\" class=\"wp-image-1426\" style=\"object-fit:cover;width:100px;height:100px\"\/><\/figure>\n\n\n\n\n\n\n\n\n\n\n\n\n\n<figure class=\"wp-block-image size-large is-resized\" style=\"margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"57\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/tripadvisorlogo1-free-img.png\" alt=\"tripadvisorlogo1 free img\" class=\"wp-image-1615\" style=\"object-fit:cover;width:180px;height:74px\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\" style=\"margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"57\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/yelp-free-img-1.png\" alt=\"yelp free img (1)\" class=\"wp-image-1617\" style=\"object-fit:cover;width:180px;height:74px\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\" style=\"margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"57\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/google-reviews-free-img.png\" alt=\"google reviews free img\" class=\"wp-image-1618\" style=\"object-fit:cover;width:180px;height:74px\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\" style=\"margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"57\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/tweet-free-img-1.png\" alt=\"tweet free img (1)\" class=\"wp-image-1616\" style=\"object-fit:cover;width:180px;height:74px\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\" style=\"margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px\"><img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"57\" src=\"https:\/\/fornosethi.com\/blog\/wp-content\/uploads\/2025\/11\/fb-free-imng.png\" alt=\"fb free imng\" class=\"wp-image-1614\" style=\"object-fit:cover;width:180px;height:74px\"\/><\/figure>\n\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1630","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fornosethi.com\/blog\/wp-json\/wp\/v2\/pages\/1630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fornosethi.com\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fornosethi.com\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fornosethi.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fornosethi.com\/blog\/wp-json\/wp\/v2\/comments?post=1630"}],"version-history":[{"count":2,"href":"https:\/\/fornosethi.com\/blog\/wp-json\/wp\/v2\/pages\/1630\/revisions"}],"predecessor-version":[{"id":1901,"href":"https:\/\/fornosethi.com\/blog\/wp-json\/wp\/v2\/pages\/1630\/revisions\/1901"}],"wp:attachment":[{"href":"https:\/\/fornosethi.com\/blog\/wp-json\/wp\/v2\/media?parent=1630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}